{"id":8,"date":"2019-08-13T20:11:35","date_gmt":"2019-08-13T20:11:35","guid":{"rendered":"http:\/\/craftsanddiy.skompini.com\/?page_id=8"},"modified":"2020-07-16T12:54:00","modified_gmt":"2020-07-16T18:54:00","slug":"home","status":"publish","type":"page","link":"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/","title":{"rendered":"Home"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"8\" class=\"elementor elementor-8\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-0591ccf elementor-hidden-phone elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0591ccf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-fc59744\" data-id=\"fc59744\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab4d87b elementor-widget elementor-widget-heading\" data-id=\"ab4d87b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Wine, wine... what else is there in life?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e8c94dc\" data-id=\"e8c94dc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cd876c1 elementor-widget elementor-widget-heading\" data-id=\"cd876c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">About Me<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-238a4e0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"238a4e0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-22d4b0a\" data-id=\"22d4b0a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-720ea22 elementor-grid-1 elementor-posts__hover-none elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-posts--show-avatar elementor-widget elementor-widget-posts\" data-id=\"720ea22\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;cards_columns&quot;:&quot;1&quot;,&quot;pagination_type&quot;:&quot;numbers_and_prev_next&quot;,&quot;cards_columns_tablet&quot;:&quot;2&quot;,&quot;cards_columns_mobile&quot;:&quot;1&quot;,&quot;cards_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;cards_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;cards_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.cards\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-cards elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-1 post type-post status-publish format-standard has-post-thumbnail hentry category-category-7\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/hello-world\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img fetchpriority=\"high\" decoding=\"async\" width=\"682\" height=\"1024\" src=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/white-wine-682x1024.jpg\" class=\"attachment-large size-large wp-image-2818\" alt=\"White wine\" srcset=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/white-wine-682x1024.jpg 682w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/white-wine-200x300.jpg 200w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/white-wine-768x1152.jpg 768w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/white-wine-1024x1536.jpg 1024w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/white-wine.jpg 1333w\" sizes=\"(max-width: 682px) 100vw, 682px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Whites<\/div>\n\t\t\t\t<div class=\"elementor-post__avatar\">\n\t\t\t<img alt='Website Administrator' src='https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/Screen-Shot-2020-07-15-at-7.14.26-PM-150x150.png' srcset='https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/Screen-Shot-2020-07-15-at-7.14.26-PM.png 2x' class='avatar avatar-128 photo' height='128' width='128' \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/hello-world\/\" >\n\t\t\t\tNeil Ellis Op Sy Moer 2016, a distinctive white bottled with fine lees\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Lorem ipsum dolor sit amet, consectetur adipiscing elit. Mauris a libero quis lacus elementum luctus facilisis condimentum tellus. Nunc vulputate malesuada est ut feugiat. Praesent<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/hello-world\/\" aria-label=\"Read more about Neil Ellis Op Sy Moer 2016, a distinctive white bottled with fine lees\" tabindex=\"-1\" >\n\t\t\tRead More \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-author\">\n\t\t\tWebsite Administrator\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-559 post type-post status-publish format-standard has-post-thumbnail hentry category-category-2\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/post-9\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"800\" height=\"552\" src=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/red-wine-bottle-and-wine-glasses-1024x706.jpg\" class=\"attachment-large size-large wp-image-2721\" alt=\"Red wine bottle and wine glasses\" srcset=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/red-wine-bottle-and-wine-glasses-1024x706.jpg 1024w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/red-wine-bottle-and-wine-glasses-300x207.jpg 300w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/red-wine-bottle-and-wine-glasses-768x530.jpg 768w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/red-wine-bottle-and-wine-glasses-1536x1059.jpg 1536w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/red-wine-bottle-and-wine-glasses.jpg 2000w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Wine Reviews<\/div>\n\t\t\t\t<div class=\"elementor-post__avatar\">\n\t\t\t<img alt='Website Administrator' src='https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/Screen-Shot-2020-07-15-at-7.14.26-PM-150x150.png' srcset='https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/Screen-Shot-2020-07-15-at-7.14.26-PM.png 2x' class='avatar avatar-128 photo' height='128' width='128' \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/post-9\/\" >\n\t\t\t\tWines for Week of 4\/12\/20\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Lorem ipsum dolor sit amet, consectetur adipiscing elit. Mauris a libero quis lacus elementum luctus facilisis condimentum tellus. Nunc vulputate malesuada est ut feugiat. Praesent<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/post-9\/\" aria-label=\"Read more about Wines for Week of 4\/12\/20\" tabindex=\"-1\" >\n\t\t\tRead More \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-author\">\n\t\t\tWebsite Administrator\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-565 post type-post status-publish format-standard has-post-thumbnail hentry category-category-3\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/post-12\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/refreshing-pink-ros-wine-1024x682.jpg\" class=\"attachment-large size-large wp-image-2760\" alt=\"Refreshing Pink Ros\u00e9 Wine\" srcset=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/refreshing-pink-ros-wine-1024x682.jpg 1024w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/refreshing-pink-ros-wine-300x200.jpg 300w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/refreshing-pink-ros-wine-768x512.jpg 768w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/refreshing-pink-ros-wine-1536x1024.jpg 1536w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/refreshing-pink-ros-wine.jpg 2000w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Rose<\/div>\n\t\t\t\t<div class=\"elementor-post__avatar\">\n\t\t\t<img alt='Website Administrator' src='https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/Screen-Shot-2020-07-15-at-7.14.26-PM-150x150.png' srcset='https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/Screen-Shot-2020-07-15-at-7.14.26-PM.png 2x' class='avatar avatar-128 photo' height='128' width='128' \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/post-12\/\" >\n\t\t\t\tSome nice high-end ros\u00e9s\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Lorem ipsum dolor sit amet, consectetur adipiscing elit. Mauris a libero quis lacus elementum luctus facilisis condimentum tellus. Nunc vulputate malesuada est ut feugiat. Praesent<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/post-12\/\" aria-label=\"Read more about Some nice high-end ros\u00e9s\" tabindex=\"-1\" >\n\t\t\tRead More \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-author\">\n\t\t\tWebsite Administrator\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-593 post type-post status-publish format-standard has-post-thumbnail hentry category-category-1\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/post-26\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/rustic-brown-wine-corks-1024x682.jpg\" class=\"attachment-large size-large wp-image-2792\" alt=\"Rustic Brown Wine Corks\" srcset=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/rustic-brown-wine-corks-1024x682.jpg 1024w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/rustic-brown-wine-corks-300x200.jpg 300w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/rustic-brown-wine-corks-768x512.jpg 768w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/rustic-brown-wine-corks-1536x1024.jpg 1536w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/rustic-brown-wine-corks.jpg 2000w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Wine News<\/div>\n\t\t\t\t<div class=\"elementor-post__avatar\">\n\t\t\t<img alt='Website Administrator' src='https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/Screen-Shot-2020-07-15-at-7.14.26-PM-150x150.png' srcset='https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/Screen-Shot-2020-07-15-at-7.14.26-PM.png 2x' class='avatar avatar-128 photo' height='128' width='128' \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/post-26\/\" >\n\t\t\t\tAre anti-cork sentiments softening in New Zealand and Australia?\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Lorem ipsum dolor sit amet, consectetur adipiscing elit. Mauris a libero quis lacus elementum luctus facilisis condimentum tellus. Nunc vulputate malesuada est ut feugiat. Praesent<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/post-26\/\" aria-label=\"Read more about Are anti-cork sentiments softening in New Zealand and Australia?\" tabindex=\"-1\" >\n\t\t\tRead More \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-author\">\n\t\t\tWebsite Administrator\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-567 post type-post status-publish format-standard has-post-thumbnail hentry category-category-6\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/post-13\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/red-wine-pouring-into-wine-glass-1024x682.jpg\" class=\"attachment-large size-large wp-image-2741\" alt=\"Red Wine Pouring Into Wine Glass\" srcset=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/red-wine-pouring-into-wine-glass-1024x682.jpg 1024w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/red-wine-pouring-into-wine-glass-300x200.jpg 300w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/red-wine-pouring-into-wine-glass-768x512.jpg 768w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/red-wine-pouring-into-wine-glass-1536x1024.jpg 1536w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/red-wine-pouring-into-wine-glass.jpg 2000w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Reds<\/div>\n\t\t\t\t<div class=\"elementor-post__avatar\">\n\t\t\t<img alt='Website Administrator' src='https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/Screen-Shot-2020-07-15-at-7.14.26-PM-150x150.png' srcset='https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/Screen-Shot-2020-07-15-at-7.14.26-PM.png 2x' class='avatar avatar-128 photo' height='128' width='128' \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/post-13\/\" >\n\t\t\t\tNapa\u2019s Royal Cabernets: The Wines of Oakville\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Lorem ipsum dolor sit amet, consectetur adipiscing elit. Mauris a libero quis lacus elementum luctus facilisis condimentum tellus. Nunc vulputate malesuada est ut feugiat. Praesent<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/post-13\/\" aria-label=\"Read more about Napa\u2019s Royal Cabernets: The Wines of Oakville\" tabindex=\"-1\" >\n\t\t\tRead More \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-author\">\n\t\t\tWebsite Administrator\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-595 post type-post status-publish format-standard has-post-thumbnail hentry category-category-1\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/post-27\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"531\" src=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/winemaker-tasting-wine-1024x680.jpg\" class=\"attachment-large size-large wp-image-2794\" alt=\"Winemaker tasting wine\" srcset=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/winemaker-tasting-wine-1024x680.jpg 1024w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/winemaker-tasting-wine-300x199.jpg 300w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/winemaker-tasting-wine-768x510.jpg 768w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/winemaker-tasting-wine-1536x1020.jpg 1536w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/winemaker-tasting-wine.jpg 2000w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Wine News<\/div>\n\t\t\t\t<div class=\"elementor-post__avatar\">\n\t\t\t<img alt='Website Administrator' src='https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/Screen-Shot-2020-07-15-at-7.14.26-PM-150x150.png' srcset='https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/Screen-Shot-2020-07-15-at-7.14.26-PM.png 2x' class='avatar avatar-128 photo' height='128' width='128' \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/post-27\/\" >\n\t\t\t\tWine tasters are made, not born\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Lorem ipsum dolor sit amet, consectetur adipiscing elit. Mauris a libero quis lacus elementum luctus facilisis condimentum tellus. Nunc vulputate malesuada est ut feugiat. Praesent<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/post-27\/\" aria-label=\"Read more about Wine tasters are made, not born\" tabindex=\"-1\" >\n\t\t\tRead More \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-author\">\n\t\t\tWebsite Administrator\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t<div class=\"e-load-more-anchor\" data-page=\"1\" data-max-page=\"10\" data-next-page=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-json\/wp\/v2\/pages\/8\/page\/2\/\"><\/div>\n\t\t\t\t<nav class=\"elementor-pagination\" aria-label=\"Pagination\">\n\t\t\t<span class=\"page-numbers prev\">&laquo; Previous<\/span>\n<span aria-current=\"page\" class=\"page-numbers current\"><span class=\"elementor-screen-only\">Page<\/span>1<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-json\/wp\/v2\/pages\/8\/page\/2\/\"><span class=\"elementor-screen-only\">Page<\/span>2<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-json\/wp\/v2\/pages\/8\/page\/3\/\"><span class=\"elementor-screen-only\">Page<\/span>3<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-json\/wp\/v2\/pages\/8\/page\/4\/\"><span class=\"elementor-screen-only\">Page<\/span>4<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-json\/wp\/v2\/pages\/8\/page\/5\/\"><span class=\"elementor-screen-only\">Page<\/span>5<\/a>\n<a class=\"page-numbers next\" href=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-json\/wp\/v2\/pages\/8\/page\/2\/\">Next &raquo;<\/a>\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e839580\" data-id=\"e839580\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e06c323 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"e06c323\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1151\" src=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/winemaker-sm-768x1151.jpg\" class=\"attachment-medium_large size-medium_large wp-image-2915\" alt=\"\" srcset=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/winemaker-sm-768x1151.jpg 768w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/winemaker-sm-200x300.jpg 200w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/winemaker-sm-683x1024.jpg 683w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/winemaker-sm-1025x1536.jpg 1025w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/winemaker-sm-1367x2048.jpg 1367w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/winemaker-sm.jpg 1637w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Hello everyone. I'm Vino.<\/h3><p class=\"elementor-image-box-description\">I'm a master wine maker and passionate wine afficionado, and I love to share what I've created and learned along the way. Welcome to my vineyard!<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f5e80a5 elementor-widget elementor-widget-spacer\" data-id=\"f5e80a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-3a96086 elementor-hidden-phone elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3a96086\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-d0b9668\" data-id=\"d0b9668\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-37ad022 elementor-widget elementor-widget-text-editor\" data-id=\"37ad022\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center; line-height: 2;\"><span style=\"font-size: 30px;\">Never want to miss\n<\/span><span style=\"font-size: 50px; line-height: 1; letter-spacing: -2.9px;\">the latest wine?<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 30px;\">Sign up for updates!<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-5fad74b elementor-hidden-phone elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"5fad74b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"Opt in gift\" aria-label=\"Opt in gift\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"8\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"5fad74b\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"\" \/>\n\n\t\t\t\t\t\t\t<input type=\"hidden\" name=\"queried_id\" value=\"8\"\/>\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tFirst Name\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"First Name\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tEmail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Email\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Yes, please.<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-16a22b0 elementor-widget elementor-widget-spacer\" data-id=\"16a22b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8269598 elementor-flip-box--effect-fade elementor-widget elementor-widget-flip-box\" data-id=\"8269598\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-flip-box\" tabindex=\"0\">\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__front\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper elementor-view-default\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-flip-box__layer__title\">\n\t\t\t\t\t\t\t\tBecome a Certified Sommelier\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-flip-box__layer__description\">\n\t\t\t\t\t\t\t\tHave you ever dreamed about sinking your tastebuds into wine for real? Find out more.\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__back\">\n\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-flip-box__layer__description\">\n\t\t\t\t\t\t\tHave you done the Wine Spirit Education Trust (WSET) study program?<\/br><\/br>\n\nAdd wine list creation and management, wine and food pairing, and wine service standards to your arsenal of wine knowledge with our Sommelier Certification Course.\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-flip-box__button elementor-button elementor-size-sm\" href=\"https:\/\/wineeducationinstitute.com\" target=\"_blank\">\n\t\t\t\t\t\t\tLearn More\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bae6906 elementor-widget elementor-widget-spacer\" data-id=\"bae6906\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-65bb2bc elementor-widget elementor-widget-heading\" data-id=\"65bb2bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">How to pour wine like a sommelier<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-75a4eb0 elementor-widget elementor-widget-video\" data-id=\"75a4eb0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;show_image_overlay&quot;:&quot;yes&quot;,&quot;image_overlay&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/samples.skompini.com\\\/prodotto-wine-blog\\\/wp-content\\\/uploads\\\/sites\\\/26\\\/2020\\\/07\\\/Screen-Shot-2020-07-16-at-9.19.34-AM.png&quot;,&quot;id&quot;:2965,&quot;size&quot;:&quot;&quot;},&quot;video_type&quot;:&quot;vimeo&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<iframe class=\"elementor-video-iframe\" allowfullscreen allow=\"clipboard-write\" title=\"vimeo Video Player\" src=\"https:\/\/player.vimeo.com\/video\/275584388?color&amp;autopause=0&amp;loop=0&amp;muted=0&amp;title=1&amp;portrait=1&amp;byline=1#t=\"><\/iframe>\t\t\t\t<div class=\"elementor-custom-embed-image-overlay\" style=\"background-image: url(https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/Screen-Shot-2020-07-16-at-9.19.34-AM.png);\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-custom-embed-play\" role=\"button\" aria-label=\"Play Video\" tabindex=\"0\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-play\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-670ab8c elementor-widget elementor-widget-spacer\" data-id=\"670ab8c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46eeffd elementor-widget elementor-widget-heading\" data-id=\"46eeffd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">What people are saying<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f6c697 elementor-arrows-yes elementor-pagination-type-bullets elementor-review--has-separator elementor--star-style-star_fontawesome elementor-widget elementor-widget-reviews\" data-id=\"7f6c697\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;show_arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"reviews.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial elementor-repeater-item-e87c3d0\">\n\t\t\t\t\t\t\t<a class=\"elementor-testimonial__header\" href=\"#\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/portrait-of-comfortable-older-woman-sitting-on-couch.jpg\" alt=\"Mary Doe\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Mary Doe<\/span><span class=\"elementor-testimonial__title\">@username<\/span><\/cite>\t\t\t\t\t<div class=\"elementor-testimonial__icon elementor-icon elementor-icon-twitter\" aria-label=\"Read More\"><i aria-hidden=\"true\" class=\"fab fa-twitter\"><\/i><\/div>\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\tI took the course on wine pairing and it's fabulous! I've never enjoyed my food more!\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial elementor-repeater-item-aa04254\">\n\t\t\t\t\t\t\t<a class=\"elementor-testimonial__header\" href=\"#\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/senior-man-smiling-at-home.jpg\" alt=\"Marcus Jones\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Marcus Jones<\/span><span class=\"elementor-testimonial__title\">@username<\/span><\/cite>\t\t\t\t\t<div class=\"elementor-testimonial__icon elementor-icon elementor-icon-twitter\" aria-label=\"Read More\"><i aria-hidden=\"true\" class=\"fab fa-twitter\"><\/i><\/div>\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\tI love reading all the latest news on wines. Vino here knows so much, and I've learned more than I could have imagined just from reading this blog.\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial elementor-repeater-item-0c19ac6\">\n\t\t\t\t\t\t\t<a class=\"elementor-testimonial__header\" href=\"#\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/handsome-older-man-smiling-with-hand-to-chin.jpg\" alt=\"Jackson Sweet\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Jackson Sweet<\/span><span class=\"elementor-testimonial__title\">@username<\/span><\/cite>\t\t\t\t\t<div class=\"elementor-testimonial__icon elementor-icon elementor-icon-twitter\" aria-label=\"Read More\"><i aria-hidden=\"true\" class=\"fab fa-twitter\"><\/i><\/div>\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\tI tell you, it's awesome knowing how to properly pour wine now. Who knew? On dates I feel like a star.\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial elementor-repeater-item-9a3a197\">\n\t\t\t\t\t\t\t<a class=\"elementor-testimonial__header\" href=\"#\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/handsome-older-man-in-suit-with-big-smile-on-his-face.jpg\" alt=\"John Markson\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">John Markson<\/span><span class=\"elementor-testimonial__title\">@username<\/span><\/cite>\t\t\t\t\t<div class=\"elementor-testimonial__icon elementor-icon elementor-icon-twitter\" aria-label=\"Read More\"><i aria-hidden=\"true\" class=\"fab fa-twitter\"><\/i><\/div>\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\tVino knows so much it blows my mind. He's so generous in sharing his knowledge. Love this blog!\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Previous\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Next\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e2fc06 elementor-widget elementor-widget-spacer\" data-id=\"2e2fc06\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3585a20 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"3585a20\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1233\" src=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/flat-lay-of-rose-wine-in-different-colors-in-glasses.jpg\" class=\"attachment-full size-full wp-image-2967\" alt=\"Flat-lay of rose wine in different colors in glasses\" srcset=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/flat-lay-of-rose-wine-in-different-colors-in-glasses.jpg 2000w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/flat-lay-of-rose-wine-in-different-colors-in-glasses-300x185.jpg 300w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/flat-lay-of-rose-wine-in-different-colors-in-glasses-1024x631.jpg 1024w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/flat-lay-of-rose-wine-in-different-colors-in-glasses-768x473.jpg 768w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/flat-lay-of-rose-wine-in-different-colors-in-glasses-1536x947.jpg 1536w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"#\">Learn how to pair wine with food<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42ddfe8 elementor-widget elementor-widget-spacer\" data-id=\"42ddfe8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-f327bbb elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"f327bbb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-563ef97\" data-id=\"563ef97\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-44f5171 elementor-widget elementor-widget-heading\" data-id=\"44f5171\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-xl\">What else can we tantalize you with?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-43a1071 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"43a1071\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-74f9ef5\" data-id=\"74f9ef5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0cc7d69 elementor-grid-4 elementor-posts--align-center elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-widget elementor-widget-posts\" data-id=\"0cc7d69\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;classic_columns&quot;:&quot;4&quot;,&quot;classic_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:51,&quot;sizes&quot;:[]},&quot;classic_columns_tablet&quot;:&quot;2&quot;,&quot;classic_columns_mobile&quot;:&quot;1&quot;,&quot;classic_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-classic elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-591 post type-post status-publish format-standard has-post-thumbnail hentry category-subcategory-1\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/post-25\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/champagne-glasses-and-red-caviar-768x512.jpg\" class=\"attachment-medium_large size-medium_large wp-image-2786\" alt=\"Champagne glasses and red caviar\" srcset=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/champagne-glasses-and-red-caviar-768x512.jpg 768w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/champagne-glasses-and-red-caviar-300x200.jpg 300w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/champagne-glasses-and-red-caviar-1024x682.jpg 1024w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/champagne-glasses-and-red-caviar-1536x1024.jpg 1536w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/champagne-glasses-and-red-caviar.jpg 2000w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/post-25\/\" >\n\t\t\t\tChampagne Castelnau R\u00e9serve NV\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-563 post type-post status-publish format-standard has-post-thumbnail hentry category-category-5\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/post-11\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/red-wine-bottle-and-glass-on-table-in-vineyard-tuscany-italy-768x512.jpg\" class=\"attachment-medium_large size-medium_large wp-image-2848\" alt=\"Red wine bottle and glass on table in vineyard Tuscany Italy\" srcset=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/red-wine-bottle-and-glass-on-table-in-vineyard-tuscany-italy-768x512.jpg 768w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/red-wine-bottle-and-glass-on-table-in-vineyard-tuscany-italy-300x200.jpg 300w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/red-wine-bottle-and-glass-on-table-in-vineyard-tuscany-italy-1024x682.jpg 1024w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/red-wine-bottle-and-glass-on-table-in-vineyard-tuscany-italy-1536x1024.jpg 1536w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/red-wine-bottle-and-glass-on-table-in-vineyard-tuscany-italy.jpg 2000w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/post-11\/\" >\n\t\t\t\tMountain Wines of Italy: Tasting Notes from Alto Adige\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-603 post type-post status-publish format-standard has-post-thumbnail hentry category-category-3\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/post-31\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1146\" src=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/rose-wine-glass-on-a-stone-wall-768x1146.jpg\" class=\"attachment-medium_large size-medium_large wp-image-2762\" alt=\"Rose wine glass on a stone wall\" srcset=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/rose-wine-glass-on-a-stone-wall-768x1146.jpg 768w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/rose-wine-glass-on-a-stone-wall-201x300.jpg 201w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/rose-wine-glass-on-a-stone-wall-686x1024.jpg 686w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/rose-wine-glass-on-a-stone-wall-1029x1536.jpg 1029w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/rose-wine-glass-on-a-stone-wall.jpg 1340w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/post-31\/\" >\n\t\t\t\tFive Reasons Why Provence Ros\u00e9 is Like Champagne\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-2114 post type-post status-publish format-standard has-post-thumbnail hentry category-category-2\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/test13\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"546\" src=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/celebration-hands-holding-the-glasses-of-champagne-and-wine-making-a-toast--768x546.jpg\" class=\"attachment-medium_large size-medium_large wp-image-2736\" alt=\"Celebration. Hands holding the glasses of champagne and wine making a toast.\" srcset=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/celebration-hands-holding-the-glasses-of-champagne-and-wine-making-a-toast--768x546.jpg 768w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/celebration-hands-holding-the-glasses-of-champagne-and-wine-making-a-toast--300x213.jpg 300w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/celebration-hands-holding-the-glasses-of-champagne-and-wine-making-a-toast--1024x728.jpg 1024w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/celebration-hands-holding-the-glasses-of-champagne-and-wine-making-a-toast--1536x1091.jpg 1536w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/celebration-hands-holding-the-glasses-of-champagne-and-wine-making-a-toast-.jpg 2000w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/test13\/\" >\n\t\t\t\tWines for Week of 1\/2\/19\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-2106 post type-post status-publish format-standard has-post-thumbnail hentry category-category-1\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/sample-post-10\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"465\" src=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/bottle-cap-on-white-background-768x465.jpg\" class=\"attachment-medium_large size-medium_large wp-image-2808\" alt=\"Bottle cap on white background\" srcset=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/bottle-cap-on-white-background-768x465.jpg 768w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/bottle-cap-on-white-background-300x182.jpg 300w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/bottle-cap-on-white-background-1024x620.jpg 1024w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/bottle-cap-on-white-background-1536x929.jpg 1536w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/bottle-cap-on-white-background.jpg 2000w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/sample-post-10\/\" >\n\t\t\t\tComparing the same wine sealed with cork and screwcap\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-609 post type-post status-publish format-standard has-post-thumbnail hentry category-subcategory-1\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/post-34\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/roses-and-champagne-768x512.jpg\" class=\"attachment-medium_large size-medium_large wp-image-2788\" alt=\"Roses and champagne\" srcset=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/roses-and-champagne-768x512.jpg 768w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/roses-and-champagne-300x200.jpg 300w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/roses-and-champagne-1024x682.jpg 1024w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/roses-and-champagne-1536x1024.jpg 1536w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/roses-and-champagne.jpg 2000w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/post-34\/\" >\n\t\t\t\tTwo impressive sparkling wines from Schramsberg\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-605 post type-post status-publish format-standard has-post-thumbnail hentry category-category-3\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/post-32\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/man-offering-a-glass-of-rose-wine-768x512.jpg\" class=\"attachment-medium_large size-medium_large wp-image-2780\" alt=\"man offering a glass of rose wine\" srcset=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/man-offering-a-glass-of-rose-wine-768x512.jpg 768w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/man-offering-a-glass-of-rose-wine-300x200.jpg 300w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/man-offering-a-glass-of-rose-wine-1024x682.jpg 1024w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/man-offering-a-glass-of-rose-wine-1536x1024.jpg 1536w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/man-offering-a-glass-of-rose-wine.jpg 2000w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/post-32\/\" >\n\t\t\t\t2003 Domaine Tempier Bandol Rose, Bandol (Provence), France\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-557 post type-post status-publish format-standard has-post-thumbnail hentry category-category-5\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/post-8\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"513\" src=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/ripe-grapes-in-fall-in-alsace-france-768x513.jpg\" class=\"attachment-medium_large size-medium_large wp-image-2843\" alt=\"Ripe grapes in fall in Alsace, France\" srcset=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/ripe-grapes-in-fall-in-alsace-france-768x513.jpg 768w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/ripe-grapes-in-fall-in-alsace-france-300x200.jpg 300w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/ripe-grapes-in-fall-in-alsace-france-1024x684.jpg 1024w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/ripe-grapes-in-fall-in-alsace-france-1536x1025.jpg 1536w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/ripe-grapes-in-fall-in-alsace-france.jpg 2000w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/post-8\/\" >\n\t\t\t\tTasting Organic Ros\u00e9 Wines from the South of France\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-601 post type-post status-publish format-standard has-post-thumbnail hentry category-category-6\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/post-30\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1265\" src=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/italian-pasta-dinner-with-spaghetti-meatballs-and-red-wine-768x1265.jpg\" class=\"attachment-medium_large size-medium_large wp-image-2758\" alt=\"Italian pasta dinner with spaghetti, meatballs and red wine\" srcset=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/italian-pasta-dinner-with-spaghetti-meatballs-and-red-wine-768x1265.jpg 768w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/italian-pasta-dinner-with-spaghetti-meatballs-and-red-wine-182x300.jpg 182w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/italian-pasta-dinner-with-spaghetti-meatballs-and-red-wine-622x1024.jpg 622w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/italian-pasta-dinner-with-spaghetti-meatballs-and-red-wine-932x1536.jpg 932w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/italian-pasta-dinner-with-spaghetti-meatballs-and-red-wine.jpg 1214w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/post-30\/\" >\n\t\t\t\tStella di Campalto, Castelnuovo dell\u2019Abate, Italy\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-2108 post type-post status-publish format-standard has-post-thumbnail hentry category-category-6\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/sample-post-9\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"509\" src=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/red-wine-768x509.jpg\" class=\"attachment-medium_large size-medium_large wp-image-2746\" alt=\"Red wine\" srcset=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/red-wine-768x509.jpg 768w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/red-wine-300x199.jpg 300w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/red-wine-1024x678.jpg 1024w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/red-wine-1536x1018.jpg 1536w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/red-wine.jpg 2000w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/sample-post-9\/\" >\n\t\t\t\t15 Years of Argentina\u2019s Finest Malbec\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-579 post type-post status-publish format-standard has-post-thumbnail hentry category-category-4\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/post-19\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/vineyards-in-la-geria-lanzarote-island-768x512.jpg\" class=\"attachment-medium_large size-medium_large wp-image-2881\" alt=\"Vineyards in La Geria, Lanzarote Island\" srcset=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/vineyards-in-la-geria-lanzarote-island-768x512.jpg 768w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/vineyards-in-la-geria-lanzarote-island-300x200.jpg 300w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/vineyards-in-la-geria-lanzarote-island-1024x682.jpg 1024w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/vineyards-in-la-geria-lanzarote-island-1536x1024.jpg 1536w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/vineyards-in-la-geria-lanzarote-island.jpg 2000w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/post-19\/\" >\n\t\t\t\tVineyards in La Geria, Lanzarote Island\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-613 post type-post status-publish format-standard has-post-thumbnail hentry category-category-4\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/post-36\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/autumn-view-of-vineyard-rows-with-the-tree-new-zealand-768x512.jpg\" class=\"attachment-medium_large size-medium_large wp-image-2879\" alt=\"Autumn view of vineyard rows with the tree, New Zealand\" srcset=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/autumn-view-of-vineyard-rows-with-the-tree-new-zealand-768x512.jpg 768w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/autumn-view-of-vineyard-rows-with-the-tree-new-zealand-300x200.jpg 300w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/autumn-view-of-vineyard-rows-with-the-tree-new-zealand-1024x682.jpg 1024w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/autumn-view-of-vineyard-rows-with-the-tree-new-zealand-1536x1024.jpg 1536w, https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-content\/uploads\/sites\/26\/2020\/07\/autumn-view-of-vineyard-rows-with-the-tree-new-zealand.jpg 2000w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/post-36\/\" >\n\t\t\t\tPegasus Bay, Canterbury\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-31249f6 elementor-widget elementor-widget-spacer\" data-id=\"31249f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Wine, wine&#8230; what else is there in life? About Me Hello everyone. I&#8217;m Vino. I&#8217;m a master wine maker and passionate wine afficionado, and I<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-8","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-json\/wp\/v2\/pages\/8","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-json\/wp\/v2\/comments?post=8"}],"version-history":[{"count":48,"href":"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-json\/wp\/v2\/pages\/8\/revisions"}],"predecessor-version":[{"id":3013,"href":"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-json\/wp\/v2\/pages\/8\/revisions\/3013"}],"wp:attachment":[{"href":"https:\/\/skompini-samples.freedomroolz.com\/prodotto-wine-blog\/wp-json\/wp\/v2\/media?parent=8"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}